{"id":14155,"date":"2022-01-01T02:09:36","date_gmt":"2021-12-31T23:09:36","guid":{"rendered":"https:\/\/zdmaa.com\/answering-your-questions-about-lung-cancer\/"},"modified":"2022-01-02T13:49:14","modified_gmt":"2022-01-02T10:49:14","slug":"answering-your-questions-about-lung-cancer","status":"publish","type":"post","link":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/","title":{"rendered":"Rispondere alle tue domande sul cancro ai polmoni"},"content":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span class=\"\" style=\"vertical-align: inherit;\">Rispondere alle tue domande sul cancro ai polmoni<\/span><\/span><\/span><\/span><\/p>\n<div>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Gli esperti di cancro del polmone Dr. <\/span><span style=\"vertical-align: inherit;\">Il cancro del polmone \u00e8 il secondo tumore non cutaneo pi\u00f9 comune negli uomini e nelle donne americani e sappiamo che ci sono molte domande sulla malattia, da come si sviluppa a come viene trattata.<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Ecco alcune delle conversazioni avvenute su Facebook. <\/span><span style=\"vertical-align: inherit;\">Per favore, prenditi un momento per leggere il testo e condividi eventuali ulteriori domande che potresti avere nella sezione commenti di questo post sul blog. <\/span><span style=\"vertical-align: inherit;\">Il Dr. Gershenhorn e il Dr. Kiev faranno del loro meglio per rispondere.<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Una persona con cancro ai polmoni dovrebbe chiedere una seconda opinione? <\/span><span style=\"vertical-align: inherit;\">Esiste una predisposizione genetica al cancro del polmone? <\/span><span style=\"vertical-align: inherit;\">Cosa possiamo fare per porre fine allo stigma secondo cui il cancro ai polmoni \u00e8 una malattia per i fumatori? <\/span><span style=\"vertical-align: inherit;\">Mesotelioma Cancer Alliance<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L: Un<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> secondo parere non guasta mai. <\/span><span style=\"vertical-align: inherit;\">Lo devi a te stesso per assicurarti di essere ben informato. <\/span><span style=\"vertical-align: inherit;\">Non ci sono sindromi genetiche comuni ben descritte che mettono le persone a rischio di sviluppare il cancro ai polmoni. <\/span><span style=\"vertical-align: inherit;\">Pi\u00f9 continuiamo a parlare del cancro ai polmoni, delle sue cause, dei trattamenti, ecc., pi\u00f9 consapevolezza genereremo. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dr<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">P: Tutti i noduli nel polmone\/polmoni sono sempre cancerosi? <\/span><span style=\"vertical-align: inherit;\">&#8211; Deborah<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> No. <\/span><span style=\"vertical-align: inherit;\">La maggior parte non \u00e8 cancerosa. <\/span><span style=\"vertical-align: inherit;\">Se viene trovato un nodo, assicurati di consultare un esperto di polmoni. <\/span><span style=\"vertical-align: inherit;\">Puoi saperne di pi\u00f9 su come diagnostichiamo le macchie polmonari attraverso il programma presso il nostro ospedale vicino a Chicago. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">K<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Quali sono i segni del cancro ai polmoni? <\/span><span style=\"vertical-align: inherit;\">&#8211; Terry<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Per:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> tosse, mancanza di respiro, tosse con sangue, perdita di peso, affaticamento. <\/span><span style=\"vertical-align: inherit;\">Tuttavia, la maggior parte dei pazienti non mostra alcun sintomo, motivo per cui lo screening \u00e8 importante nelle persone ad alto rischio. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">K<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: <\/span><\/span><\/strong><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Che <\/span><\/span><\/strong><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">tipo di innovazione sta accadendo nel campo del cancro ai polmoni? <\/span><span style=\"vertical-align: inherit;\">&#8211; Brooke<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Il cancro del polmone si muove in due direzioni diverse: terapie mirate e immunoterapia. <\/span><span style=\"vertical-align: inherit;\">Le terapie mirate combinano farmaci e mutazioni driver identificate nel cancro di un individuo. <\/span><span style=\"vertical-align: inherit;\">Le terapie immunostimolanti utilizzano il potere del sistema immunitario per uccidere direttamente le cellule cancerose. <\/span><span style=\"vertical-align: inherit;\">Gli agenti attualmente disponibili sono molti e in fase di test sfruttano questi due diversi approcci. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dr<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Cosa hai sentito che aiuterebbe le persone a superare l&#8217;astinenza per smettere di fumare? <\/span><span style=\"vertical-align: inherit;\">&#8211; Felicia<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Un buon programma per smettere di fumare e un buon sistema di supporto sono fondamentali per combattere la dipendenza da nicotina. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">K<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Ho sempre sentito dire che il fumo \u00e8 la causa del cancro ai polmoni. <\/span><span style=\"vertical-align: inherit;\">E chi non ha mai fumato? <\/span><span style=\"vertical-align: inherit;\">&#8211; Kony<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Il cancro del polmone si sviluppa nei non fumatori, circa il 10% di loro. <\/span><span style=\"vertical-align: inherit;\">Altre cause includono amianto, radon e altre esposizioni ambientali. <\/span><span style=\"vertical-align: inherit;\">I non fumatori hanno un pi\u00f9 alto tasso di mutazioni che possono essere attaccate con le pillole rispetto alla chemioterapia convenzionale. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">Buono. <\/span><span style=\"vertical-align: inherit;\">K<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Vorrei sapere se i medici hanno usato nivolumab. <\/span><span style=\"vertical-align: inherit;\">&#8211; Ren\u00e9<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> S\u00ec. <\/span><span style=\"vertical-align: inherit;\">Al momento, \u00e8 stato approvato dalla FDA solo per il cancro del polmone a cellule squamose. <\/span><span style=\"vertical-align: inherit;\">Sono molto entusiasta del potenziale di questo farmaco. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">C<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">P: Qual \u00e8 la possibilit\u00e0 di sviluppare un cancro ai polmoni quando il tumore carcinoide viene rimosso? <\/span><span style=\"vertical-align: inherit;\">&#8211; bama<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Molto improbabile, ma dovresti essere seguito da vicino da pneumologi. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">K<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: La broncopneumopatia cronica ostruttiva (BPCO) porta direttamente al cancro ai polmoni? <\/span><span style=\"vertical-align: inherit;\">&#8211; composizione musicale<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Lo stesso fattore di rischio per la BPCO causa anche il cancro ai polmoni: il fumo. <\/span><span style=\"vertical-align: inherit;\">Pertanto, i pazienti con BPCO hanno maggiori probabilit\u00e0 di sviluppare il cancro ai polmoni. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">C<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Mia sorella ha un cancro ai polmoni allo stadio 4 con sei metastasi cerebrali e il cancro \u00e8 presente in diverse aree del suo corpo. <\/span><span style=\"vertical-align: inherit;\">Saresti o saresti un candidato per l&#8217;immunoterapia o altre terapie mirate, o funzionano solo se il cancro \u00e8 isolato? <\/span><span style=\"vertical-align: inherit;\">&#8211; Regina<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Al momento, solo le immunoterapie sono approvate per il cancro del polmone a cellule squamose. <\/span><span style=\"vertical-align: inherit;\">Tuttavia, questo \u00e8 probabile che cambi nel prossimo futuro. <\/span><span style=\"vertical-align: inherit;\">Le terapie specificamente mirate devono essere adattate alle caratteristiche del cancro del paziente. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">C<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Ho perso mio nonno, alcuni dei miei cugini e molti dei miei zii e zie a causa di un cancro ai polmoni. <\/span><span style=\"vertical-align: inherit;\">Mia madre ha il cancro al seno. <\/span><span style=\"vertical-align: inherit;\">Ho avuto un cancro pre-uterino quando avevo 16 anni. <\/span><span style=\"vertical-align: inherit;\">Anche le mie sorelle avevano diversi tipi di cancro. <\/span><span style=\"vertical-align: inherit;\">Tuttavia, perch\u00e9 si dice che il cancro non \u00e8 genetico? <\/span><span style=\"vertical-align: inherit;\">&#8211; laggi\u00f9<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Teresa, questa \u00e8 una domanda difficile. <\/span><span style=\"vertical-align: inherit;\">Consigliamo una valutazione da parte di un consulente genetico per comprendere meglio i rischi tuoi e della tua famiglia. <\/span><span style=\"vertical-align: inherit;\">Puoi saperne di pi\u00f9 sulla consulenza genetica, compresi i benefici psicologici e i rischi coinvolti. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dr<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Entrambi i miei genitori avevano il cancro ai polmoni. <\/span><span style=\"vertical-align: inherit;\">Ho 52 anni e sono un ex fumatore. <\/span><span style=\"vertical-align: inherit;\">Cosa forniscono gli esami polmonari? <\/span><span style=\"vertical-align: inherit;\">&#8211; Tracy<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L: Una<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> scansione TC dei polmoni offre l&#8217;opportunit\u00e0 di rilevare il cancro ai polmoni in una fase iniziale, il che pu\u00f2 migliorare i risultati del trattamento. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott. <\/span><span style=\"vertical-align: inherit;\">K<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">D: Qual \u00e8 la differenza tra test genetici e genomici? <\/span><span style=\"vertical-align: inherit;\">&#8211; Susan<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Pensa ai test genomici come alla presa del tumore stesso e alla comprensione dei suoi driver, perch\u00e9 la cellula \u00e8 diventata cancerosa. <\/span><span style=\"vertical-align: inherit;\">Il test del genoma ti consente di chiamarlo per il suo motore unico, il controller molecolare. <\/span><span style=\"vertical-align: inherit;\">Quindi pu\u00f2 attaccare il cancro in base a questo motore molecolare. <\/span><span style=\"vertical-align: inherit;\">Il test genetico serve a capire cosa ti hanno dato i tuoi genitori e cosa \u00e8 stato trasmesso ai tuoi figli. <\/span><span style=\"vertical-align: inherit;\">Quando si tratta di test genetici relativi al cancro del polmone, la ricerca \u00e8 in corso. <\/span><span style=\"vertical-align: inherit;\">&#8211; Dott.<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Scopri di pi\u00f9 sul cancro del polmone, incluso come viene diagnosticato e trattato.<\/span><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rispondere alle tue domande sul cancro ai polmoni Gli esperti di cancro del polmone Dr. Il cancro del polmone \u00e8 il secondo tumore non cutaneo pi\u00f9 comune negli uomini e nelle donne americani e sappiamo che ci sono molte domande sulla malattia, da come si sviluppa a come viene trattata. Ecco alcune delle conversazioni avvenute &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-14155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rispondere alle tue domande sul cancro ai polmoni - zdmaa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rispondere alle tue domande sul cancro ai polmoni - zdmaa\" \/>\n<meta property=\"og:description\" content=\"Rispondere alle tue domande sul cancro ai polmoni Gli esperti di cancro del polmone Dr. Il cancro del polmone \u00e8 il secondo tumore non cutaneo pi\u00f9 comune negli uomini e nelle donne americani e sappiamo che ci sono molte domande sulla malattia, da come si sviluppa a come viene trattata. Ecco alcune delle conversazioni avvenute &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/\" \/>\n<meta property=\"og:site_name\" content=\"zdmaa\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-31T23:09:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-02T10:49:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/question-mark-gc8ea6eb6b_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/\",\"url\":\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/\",\"name\":\"Rispondere alle tue domande sul cancro ai polmoni - zdmaa\",\"isPartOf\":{\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/question-mark-gc8ea6eb6b_640.jpg\",\"datePublished\":\"2021-12-31T23:09:36+00:00\",\"dateModified\":\"2022-01-02T10:49:14+00:00\",\"author\":{\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/8aad4cf5d562d4ca835487f6149853e3\"},\"breadcrumb\":{\"@id\":\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#primaryimage\",\"url\":\"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/question-mark-gc8ea6eb6b_640.jpg\",\"contentUrl\":\"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/question-mark-gc8ea6eb6b_640.jpg\",\"width\":640,\"height\":640,\"caption\":\"Answering your questions about lung cancer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\/\/zdmaa.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rispondere alle tue domande sul cancro ai polmoni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#website\",\"url\":\"https:\/\/zdmaa.com\/it\/ro\/\",\"name\":\"zdmaa\",\"description\":\"zdmaa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zdmaa.com\/it\/ro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/8aad4cf5d562d4ca835487f6149853e3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/zdmaa.com\/wp-content\/litespeed\/avatar\/dff6d89ac221c1aaf9366bf5b4cd32de.jpg?ver=1783817703\",\"contentUrl\":\"https:\/\/zdmaa.com\/wp-content\/litespeed\/avatar\/dff6d89ac221c1aaf9366bf5b4cd32de.jpg?ver=1783817703\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/zdmaa.com\"],\"url\":\"https:\/\/zdmaa.com\/it\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rispondere alle tue domande sul cancro ai polmoni - zdmaa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/","og_locale":"it_IT","og_type":"article","og_title":"Rispondere alle tue domande sul cancro ai polmoni - zdmaa","og_description":"Rispondere alle tue domande sul cancro ai polmoni Gli esperti di cancro del polmone Dr. Il cancro del polmone \u00e8 il secondo tumore non cutaneo pi\u00f9 comune negli uomini e nelle donne americani e sappiamo che ci sono molte domande sulla malattia, da come si sviluppa a come viene trattata. Ecco alcune delle conversazioni avvenute &hellip;","og_url":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/","og_site_name":"zdmaa","article_published_time":"2021-12-31T23:09:36+00:00","article_modified_time":"2022-01-02T10:49:14+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/question-mark-gc8ea6eb6b_640.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/","url":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/","name":"Rispondere alle tue domande sul cancro ai polmoni - zdmaa","isPartOf":{"@id":"https:\/\/zdmaa.com\/it\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#primaryimage"},"image":{"@id":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/question-mark-gc8ea6eb6b_640.jpg","datePublished":"2021-12-31T23:09:36+00:00","dateModified":"2022-01-02T10:49:14+00:00","author":{"@id":"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/8aad4cf5d562d4ca835487f6149853e3"},"breadcrumb":{"@id":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#primaryimage","url":"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/question-mark-gc8ea6eb6b_640.jpg","contentUrl":"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/question-mark-gc8ea6eb6b_640.jpg","width":640,"height":640,"caption":"Answering your questions about lung cancer"},{"@type":"BreadcrumbList","@id":"https:\/\/zdmaa.com\/it\/answering-your-questions-about-lung-cancer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/zdmaa.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rispondere alle tue domande sul cancro ai polmoni"}]},{"@type":"WebSite","@id":"https:\/\/zdmaa.com\/it\/ro\/#website","url":"https:\/\/zdmaa.com\/it\/ro\/","name":"zdmaa","description":"zdmaa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zdmaa.com\/it\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/8aad4cf5d562d4ca835487f6149853e3","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/image\/","url":"https:\/\/zdmaa.com\/wp-content\/litespeed\/avatar\/dff6d89ac221c1aaf9366bf5b4cd32de.jpg?ver=1783817703","contentUrl":"https:\/\/zdmaa.com\/wp-content\/litespeed\/avatar\/dff6d89ac221c1aaf9366bf5b4cd32de.jpg?ver=1783817703","caption":"admin"},"sameAs":["https:\/\/zdmaa.com"],"url":"https:\/\/zdmaa.com\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/posts\/14155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/comments?post=14155"}],"version-history":[{"count":2,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/posts\/14155\/revisions"}],"predecessor-version":[{"id":14172,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/posts\/14155\/revisions\/14172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/media\/13923"}],"wp:attachment":[{"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/media?parent=14155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/categories?post=14155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/tags?post=14155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}