{"id":18214,"date":"2022-01-06T14:24:56","date_gmt":"2022-01-06T11:24:56","guid":{"rendered":"https:\/\/zdmaa.com\/immunotherapy-drug-triggers-cascading-immune-response\/"},"modified":"2022-01-07T01:50:00","modified_gmt":"2022-01-06T22:50:00","slug":"immunotherapy-drug-triggers-cascading-immune-response","status":"publish","type":"post","link":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/","title":{"rendered":"Induttori farmacologici a cascata dell&#8217;immunoterapia della risposta immunitaria"},"content":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span class=\"\" style=\"vertical-align: inherit;\">Induttori farmacologici a cascata dell&#8217;immunoterapia della risposta immunitaria<\/span><\/span><\/span><\/span><\/p>\n<div>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I ricercatori hanno avviato uno studio su un farmaco immunoterapico che potrebbe aggiungere un nuovo strumento all&#8217;arsenale del sistema immunitario contro il cancro. <\/span><span style=\"vertical-align: inherit;\">Il sistema immunitario ha bisogno di ulteriore aiuto, perch\u00e9 non sempre riconosce il cancro come una minaccia e vede le cellule come propriet\u00e0 del corpo, non come mutazioni dannose che sono diventate. <\/span><span style=\"vertical-align: inherit;\">Quindi, quando le cellule tumorali passano attraverso molecole proteiche chiamate &#8220;punti di controllo&#8221;, che sono cos\u00ec chiamate perch\u00e9 &#8220;monitorano&#8221; le cellule per valutare i loro rischi per la salute del corpo, le cellule tumorali inviano segnali ingannevoli che imitano le cellule normali che erano, permettendo loro di passare inosservati&#8230;<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Una promettente classe di farmaci immunoterapici noti come inibitori del checkpoint agisce interrompendo quei segnali, esponendo le cellule cancerose al sistema immunitario e scatenando un potenziale attacco. <\/span><span style=\"vertical-align: inherit;\">I farmaci immunoterapici ora sul mercato prendono di mira tre recettori checkpoint: PD-1, PD-L1 e CLTA-4. <\/span><span style=\"vertical-align: inherit;\">Questi inibitori del checkpoint sono attualmente approvati per il melanoma avanzato, il carcinoma polmonare non a piccole cellule, il carcinoma a cellule renali, il linfoma di Hodgkin, il cancro della vescica e\/o il carcinoma a cellule squamose della testa e del collo.<\/span><\/span><\/p>\n<h2><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Esplora nuove opzioni<\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Un nuovo studio di Fase 1 studia un farmaco, attualmente chiamato TSR-022, che sta cercando di bloccare un altro checkpoint che non \u00e8 ancora stato un obiettivo per un farmaco approvato: TIM-3. <\/span><span style=\"vertical-align: inherit;\">&#8220;Speriamo di ottenere molte cose&#8221;, afferma il dott. Glenn Weiss, direttore della ricerca clinica e degli studi clinici di fase I e II presso il nostro ospedale vicino a Phoenix e investigatore principale dello studio. <\/span><span style=\"vertical-align: inherit;\">&#8220;Vogliamo essere in grado di studiare nuove opzioni di trattamento per i nostri pazienti con tumori avanzati, determinare quanto \u00e8 sicuro un farmaco e come dovrebbe essere dosato e vedere se porta a risultati a lungo termine&#8221;.<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Ci\u00f2 che pu\u00f2 distinguere TSR-022 dagli inibitori del checkpoint approvati \u00e8 il potenziale effetto a cascata che pu\u00f2 produrre se suscita una risposta immunitaria. <\/span><span style=\"vertical-align: inherit;\">Secondo un articolo del 2014 pubblicato dall&#8217;American Association for Cancer Research (AACR), i recettori TIM-3 non si trovano solo nelle cellule T dei tumori, ma sono anche legati alla presenza di altre cellule che possono causare un cortocircuito nei tumori. <\/span><span style=\"vertical-align: inherit;\">sistema immune. <\/span><span style=\"vertical-align: inherit;\">e\/o promuovere la crescita del tumore. <\/span><span style=\"vertical-align: inherit;\">Pertanto, mirare a TIM-3 pu\u00f2 non solo riattivare le cellule T, ma anche portare alla creazione di altre interazioni cellulari oltre la progettazione degli attuali farmaci immunoterapici. <\/span><span style=\"vertical-align: inherit;\">Per esempio:<\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Gli scienziati ritengono che TIM-3 possa attirare le cellule T regolatorie (Treg) che si accalcano intorno al microambiente tumorale e sopprimono il sistema immunitario. <\/span><span style=\"vertical-align: inherit;\">Le Treg sono necessarie al sistema immunitario per evitare che le cellule T vengano disturbate.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Alcune ricerche suggeriscono che TIM-3 pu\u00f2 aumentare la presenza di cellule soppressorie di derivazione mieloide. <\/span><span style=\"vertical-align: inherit;\">Queste cellule aiutano a regolare il sistema immunitario, ma possono anche essere responsabili della scarsa risposta ai trattamenti contro il cancro.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">TIM-3 si trova nelle cellule dendritiche e pu\u00f2 impedire loro di avviare una risposta immunitaria. <\/span><span style=\"vertical-align: inherit;\">Le cellule dendritiche sono come la polizia stradale del sistema immunitario, inviando le cellule T nella giusta direzione per attaccare gli invasori.<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h2><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Come funzionano gli inibitori del PD-1?<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Gli inibitori del checkpoint PD-1 sono progettati per funzionare in modo causa-effetto. <\/span><span style=\"vertical-align: inherit;\">Blocca la comunicazione tra la cellula cancerosa e la cellula immunitaria al checkpoint PD-1, che porta ad un attacco alle cellule cancerose. <\/span><span style=\"vertical-align: inherit;\">dice il dottor. <\/span><span style=\"vertical-align: inherit;\">Il TSR-022 di Vice \u00e8 &#8220;progettato per avere un impatto pi\u00f9 ampio&#8221;. <\/span><span style=\"vertical-align: inherit;\">Blocca TIM-3 e la potenziale interazione pu\u00f2 assomigliare a una linea di tessere cellulari che cadono una ad una, aprendo le cellule cancerose a pi\u00f9 attacchi.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L&#8217;articolo dell&#8217;AACR afferma che TIM-3 \u00e8 presente in pazienti con melanoma, carcinoma polmonare non a piccole cellule e linfoma non Hodgkin, ma questo studio include pazienti adulti con tumori solidi che soddisfano altri requisiti specifici relativi alle precedenti terapie antitumorali. <\/span><span style=\"vertical-align: inherit;\">Lo studio studia come funziona TSR-022 da solo e in combinazione con un inibitore PD-1. <\/span><span style=\"vertical-align: inherit;\">Il nostro ospedale vicino a Phoenix \u00e8 stato il primo sito al mondo a somministrare TSR-022 come parte di uno studio clinico di fase I. TSR-022 \u00e8 stato sviluppato da TESARO Inc. <\/span><span style=\"vertical-align: inherit;\">a Waltham, Massachusetts, in associazione con AnaptysBio Inc. <\/span><span style=\"vertical-align: inherit;\">a San Diego.<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Scopri di pi\u00f9 sulla scienza dietro l&#8217;immunoterapia.<\/span><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Induttori farmacologici a cascata dell&#8217;immunoterapia della risposta immunitaria I ricercatori hanno avviato uno studio su un farmaco immunoterapico che potrebbe aggiungere un nuovo strumento all&#8217;arsenale del sistema immunitario contro il cancro. Il sistema immunitario ha bisogno di ulteriore aiuto, perch\u00e9 non sempre riconosce il cancro come una minaccia e vede le cellule come propriet\u00e0 del &hellip;<\/p>\n","protected":false},"author":1,"featured_media":17916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-18214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Induttori farmacologici a cascata dell&#039;immunoterapia della risposta immunitaria - zdmaa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Induttori farmacologici a cascata dell&#039;immunoterapia della risposta immunitaria - zdmaa\" \/>\n<meta property=\"og:description\" content=\"Induttori farmacologici a cascata dell&#8217;immunoterapia della risposta immunitaria I ricercatori hanno avviato uno studio su un farmaco immunoterapico che potrebbe aggiungere un nuovo strumento all&#8217;arsenale del sistema immunitario contro il cancro. Il sistema immunitario ha bisogno di ulteriore aiuto, perch\u00e9 non sempre riconosce il cancro come una minaccia e vede le cellule come propriet\u00e0 del &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/\" \/>\n<meta property=\"og:site_name\" content=\"zdmaa\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-06T11:24:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-06T22:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/vaccination-g948d9c78e_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"419\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/\",\"url\":\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/\",\"name\":\"Induttori farmacologici a cascata dell'immunoterapia della risposta immunitaria - zdmaa\",\"isPartOf\":{\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/vaccination-g948d9c78e_640.jpg\",\"datePublished\":\"2022-01-06T11:24:56+00:00\",\"dateModified\":\"2022-01-06T22:50:00+00:00\",\"author\":{\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/8aad4cf5d562d4ca835487f6149853e3\"},\"breadcrumb\":{\"@id\":\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#primaryimage\",\"url\":\"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/vaccination-g948d9c78e_640.jpg\",\"contentUrl\":\"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/vaccination-g948d9c78e_640.jpg\",\"width\":640,\"height\":419,\"caption\":\"Immunotherapy Drug Triggers Cascading Immune Response\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\/\/zdmaa.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Induttori farmacologici a cascata dell&#8217;immunoterapia della risposta immunitaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#website\",\"url\":\"https:\/\/zdmaa.com\/it\/ro\/\",\"name\":\"zdmaa\",\"description\":\"zdmaa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zdmaa.com\/it\/ro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/8aad4cf5d562d4ca835487f6149853e3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/zdmaa.com\/wp-content\/litespeed\/avatar\/dff6d89ac221c1aaf9366bf5b4cd32de.jpg?ver=1783817703\",\"contentUrl\":\"https:\/\/zdmaa.com\/wp-content\/litespeed\/avatar\/dff6d89ac221c1aaf9366bf5b4cd32de.jpg?ver=1783817703\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/zdmaa.com\"],\"url\":\"https:\/\/zdmaa.com\/it\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Induttori farmacologici a cascata dell'immunoterapia della risposta immunitaria - zdmaa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/","og_locale":"it_IT","og_type":"article","og_title":"Induttori farmacologici a cascata dell'immunoterapia della risposta immunitaria - zdmaa","og_description":"Induttori farmacologici a cascata dell&#8217;immunoterapia della risposta immunitaria I ricercatori hanno avviato uno studio su un farmaco immunoterapico che potrebbe aggiungere un nuovo strumento all&#8217;arsenale del sistema immunitario contro il cancro. Il sistema immunitario ha bisogno di ulteriore aiuto, perch\u00e9 non sempre riconosce il cancro come una minaccia e vede le cellule come propriet\u00e0 del &hellip;","og_url":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/","og_site_name":"zdmaa","article_published_time":"2022-01-06T11:24:56+00:00","article_modified_time":"2022-01-06T22:50:00+00:00","og_image":[{"width":640,"height":419,"url":"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/vaccination-g948d9c78e_640.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/","url":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/","name":"Induttori farmacologici a cascata dell'immunoterapia della risposta immunitaria - zdmaa","isPartOf":{"@id":"https:\/\/zdmaa.com\/it\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#primaryimage"},"image":{"@id":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#primaryimage"},"thumbnailUrl":"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/vaccination-g948d9c78e_640.jpg","datePublished":"2022-01-06T11:24:56+00:00","dateModified":"2022-01-06T22:50:00+00:00","author":{"@id":"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/8aad4cf5d562d4ca835487f6149853e3"},"breadcrumb":{"@id":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#primaryimage","url":"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/vaccination-g948d9c78e_640.jpg","contentUrl":"https:\/\/zdmaa.com\/wp-content\/uploads\/2022\/01\/vaccination-g948d9c78e_640.jpg","width":640,"height":419,"caption":"Immunotherapy Drug Triggers Cascading Immune Response"},{"@type":"BreadcrumbList","@id":"https:\/\/zdmaa.com\/it\/immunotherapy-drug-triggers-cascading-immune-response\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/zdmaa.com\/it\/"},{"@type":"ListItem","position":2,"name":"Induttori farmacologici a cascata dell&#8217;immunoterapia della risposta immunitaria"}]},{"@type":"WebSite","@id":"https:\/\/zdmaa.com\/it\/ro\/#website","url":"https:\/\/zdmaa.com\/it\/ro\/","name":"zdmaa","description":"zdmaa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zdmaa.com\/it\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/8aad4cf5d562d4ca835487f6149853e3","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/zdmaa.com\/it\/ro\/#\/schema\/person\/image\/","url":"https:\/\/zdmaa.com\/wp-content\/litespeed\/avatar\/dff6d89ac221c1aaf9366bf5b4cd32de.jpg?ver=1783817703","contentUrl":"https:\/\/zdmaa.com\/wp-content\/litespeed\/avatar\/dff6d89ac221c1aaf9366bf5b4cd32de.jpg?ver=1783817703","caption":"admin"},"sameAs":["https:\/\/zdmaa.com"],"url":"https:\/\/zdmaa.com\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/posts\/18214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/comments?post=18214"}],"version-history":[{"count":2,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/posts\/18214\/revisions"}],"predecessor-version":[{"id":18232,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/posts\/18214\/revisions\/18232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/media\/17916"}],"wp:attachment":[{"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/media?parent=18214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/categories?post=18214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zdmaa.com\/it\/wp-json\/wp\/v2\/tags?post=18214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}